{"id":265,"date":"2018-01-23T07:35:39","date_gmt":"2018-01-23T07:35:39","guid":{"rendered":"http:\/\/ceu.ijs.si\/podrocja-dela\/"},"modified":"2018-03-12T18:21:08","modified_gmt":"2018-03-12T18:21:08","slug":"expertise","status":"publish","type":"page","link":"https:\/\/ceu.ijs.si\/en\/expertise\/","title":{"rendered":"Expertise"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-podrocja-dela.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-265","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/pages\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/comments?post=265"}],"version-history":[{"count":1,"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/pages\/265\/revisions"}],"predecessor-version":[{"id":319,"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/pages\/265\/revisions\/319"}],"wp:attachment":[{"href":"https:\/\/ceu.ijs.si\/en\/wp-json\/wp\/v2\/media?parent=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}